{"id":259,"date":"2022-09-09T16:07:53","date_gmt":"2022-09-09T16:07:53","guid":{"rendered":"http:\/\/cirefluvial.com\/nuevarevista\/?p=259"},"modified":"2024-05-23T14:10:34","modified_gmt":"2024-05-23T14:10:34","slug":"evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura","status":"publish","type":"post","link":"https:\/\/restaurarios.es\/pt\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/","title":{"rendered":"Avalia\u00e7\u00e3o a m\u00e9dio prazo do sucesso da restaura\u00e7\u00e3o ribeirinha no \u00e2mbito do projeto LIFE+ RIPISILVANATURA"},"content":{"rendered":"<p class=\" translation-block\">As margens dos rios s\u00e3o \u00e1reas de grande interesse ecol\u00f3gico, mas sua modifica\u00e7\u00e3o antr\u00f3pica levou ao estabelecimento de esp\u00e9cies invasoras, como <em>Arundo donax<\/em> L. na bacia do rio Segura (SE Espanha), com efeitos prejudiciais sobre a biodiversidade. Perante este problema, no \u00e2mbito do projeto LIFE+ RIPISILVANATURA (2015-2019), foram realizadas a\u00e7\u00f5es de controlo de cana e planta\u00e7\u00f5es com esp\u00e9cies aut\u00f3ctones no tro\u00e7o m\u00e9dio do rio Segura. Neste trabalho, \u00e9 realizado um acompanhamento a m\u00e9dio prazo ap\u00f3s dois anos do t\u00e9rmino do projeto e da cessa\u00e7\u00e3o ou flexibiliza\u00e7\u00e3o das tarefas de manuten\u00e7\u00e3o (limpeza da cana) em 8 das esta\u00e7\u00f5es restauradas para avaliar o grau de sucesso alcan\u00e7ado comparado com as condi\u00e7\u00f5es de refer\u00eancia. Para detetar diferen\u00e7as temporais na composi\u00e7\u00e3o e abund\u00e2ncia de esp\u00e9cies em esta\u00e7\u00f5es revegetadas e de refer\u00eancia foram aplicadas an\u00e1lises de escala multidimensional n\u00e3o m\u00e9trica (NMDS) e modelos lineares generalizados para dados de abund\u00e2ncia (GLM). Para determinar se a altura m\u00e9dia das esp\u00e9cies plantadas difere entre as esta\u00e7\u00f5es com ou sem manuten\u00e7\u00e3o, foram aplicadas ANOVAs. Al\u00e9m disso, as mudan\u00e7as temporais em diferentes indicadores ecol\u00f3gicos e o efeito da continua\u00e7\u00e3o ou n\u00e3o da manuten\u00e7\u00e3o foram determinados usando modelos lineares de efeitos mistos. Ap\u00f3s 6 anos desde o in\u00edcio e 2 anos desde o final do projeto, o sucesso alcan\u00e7ado foi relativamente baixo. Embora atualmente a composi\u00e7\u00e3o da vegeta\u00e7\u00e3o das esta\u00e7\u00f5es restauradas tenda a ser mais semelhante \u00e0 das comunidades de refer\u00eancia, nos \u00faltimos anos a aus\u00eancia de manuten\u00e7\u00e3o produziu um aumento na cobertura, densidade e altura de A. donax, bem como uma diminui\u00e7\u00e3o da riqueza de esp\u00e9cies e mau estado ecol\u00f3gico das margens dos rios. Portanto, um programa de manuten\u00e7\u00e3o e monitora\u00e7\u00e3o de m\u00e9dio longo prazo \u00e9 essencial para melhorar o sucesso de futuros projetos de restaura\u00e7\u00e3o das margens do rio.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":15,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[16,18,17,15,19],"class_list":["post-259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volumen-2","tag-especies-invasoras","tag-monitoreo-ecologico","tag-restauracion-ecologica","tag-riberas-fluviales","tag-vegetacion-riberena"],"acf":[],"gutentor_comment":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA - Revista RestauraRios - CIREF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/restaurarios.es\/pt\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA - Revista RestauraRios - CIREF\" \/>\n<meta property=\"og:url\" content=\"https:\/\/restaurarios.es\/pt\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista RestauraRios - CIREF\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-09T16:07:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T14:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"904\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fixer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fixer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/\"},\"author\":{\"name\":\"fixer\",\"@id\":\"https:\/\/restaurarios.es\/#\/schema\/person\/9c0a72e763764be8ca350ac61d81581d\"},\"headline\":\"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA\",\"datePublished\":\"2022-09-09T16:07:53+00:00\",\"dateModified\":\"2024-05-23T14:10:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/\"},\"wordCount\":353,\"publisher\":{\"@id\":\"https:\/\/restaurarios.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg\",\"keywords\":[\"Especies invasoras\",\"Monitoreo ecol\u00f3gico\",\"Restauraci\u00f3n ecol\u00f3gica\",\"Riberas fluviales\",\"Vegetaci\u00f3n ribere\u00f1a\"],\"articleSection\":[\"Volumen 2 (2021)\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/\",\"url\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/\",\"name\":\"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA - Revista RestauraRios - CIREF\",\"isPartOf\":{\"@id\":\"https:\/\/restaurarios.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg\",\"datePublished\":\"2022-09-09T16:07:53+00:00\",\"dateModified\":\"2024-05-23T14:10:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#primaryimage\",\"url\":\"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg\",\"contentUrl\":\"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg\",\"width\":640,\"height\":904,\"caption\":\"Portada revista 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/restaurarios.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/restaurarios.es\/#website\",\"url\":\"https:\/\/restaurarios.es\/\",\"name\":\"Revista RestauraRios - CIREF\",\"description\":\"Revista de conservaci\u00f3n y restauraci\u00f3n fluvial\",\"publisher\":{\"@id\":\"https:\/\/restaurarios.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/restaurarios.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/restaurarios.es\/#organization\",\"name\":\"Revista RestauraRios - CIREF\",\"url\":\"https:\/\/restaurarios.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/restaurarios.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/cabecera-960px.jpg\",\"contentUrl\":\"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/cabecera-960px.jpg\",\"width\":960,\"height\":214,\"caption\":\"Revista RestauraRios - CIREF\"},\"image\":{\"@id\":\"https:\/\/restaurarios.es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/restaurarios.es\/#\/schema\/person\/9c0a72e763764be8ca350ac61d81581d\",\"name\":\"fixer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/restaurarios.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g\",\"caption\":\"fixer\"},\"sameAs\":[\"http:\/\/cirefluvial.com\/nuevarevista\"],\"url\":\"https:\/\/restaurarios.es\/pt\/author\/fixer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA - Revista RestauraRios - CIREF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/restaurarios.es\/pt\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/","og_locale":"pt_PT","og_type":"article","og_title":"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA - Revista RestauraRios - CIREF","og_url":"https:\/\/restaurarios.es\/pt\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/","og_site_name":"Revista RestauraRios - CIREF","article_published_time":"2022-09-09T16:07:53+00:00","article_modified_time":"2024-05-23T14:10:34+00:00","og_image":[{"width":640,"height":904,"url":"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg","type":"image\/jpeg"}],"author":"fixer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fixer","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#article","isPartOf":{"@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/"},"author":{"name":"fixer","@id":"https:\/\/restaurarios.es\/#\/schema\/person\/9c0a72e763764be8ca350ac61d81581d"},"headline":"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA","datePublished":"2022-09-09T16:07:53+00:00","dateModified":"2024-05-23T14:10:34+00:00","mainEntityOfPage":{"@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/"},"wordCount":353,"publisher":{"@id":"https:\/\/restaurarios.es\/#organization"},"image":{"@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#primaryimage"},"thumbnailUrl":"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg","keywords":["Especies invasoras","Monitoreo ecol\u00f3gico","Restauraci\u00f3n ecol\u00f3gica","Riberas fluviales","Vegetaci\u00f3n ribere\u00f1a"],"articleSection":["Volumen 2 (2021)"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/","url":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/","name":"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA - Revista RestauraRios - CIREF","isPartOf":{"@id":"https:\/\/restaurarios.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#primaryimage"},"image":{"@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#primaryimage"},"thumbnailUrl":"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg","datePublished":"2022-09-09T16:07:53+00:00","dateModified":"2024-05-23T14:10:34+00:00","breadcrumb":{"@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#primaryimage","url":"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg","contentUrl":"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/restaurarios-02-portada-pichi.jpg","width":640,"height":904,"caption":"Portada revista 2"},{"@type":"BreadcrumbList","@id":"https:\/\/restaurarios.es\/evaluacion-a-medio-plazo-del-exito-de-la-restauracion-de-riberas-en-el-ambito-del-proyecto-life-ripisilvanatura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/restaurarios.es\/"},{"@type":"ListItem","position":2,"name":"Evaluaci\u00f3n a medio plazo del \u00e9xito de la restauraci\u00f3n de riberas en el \u00e1mbito del proyecto LIFE+ RIPISILVANATURA"}]},{"@type":"WebSite","@id":"https:\/\/restaurarios.es\/#website","url":"https:\/\/restaurarios.es\/","name":"Revista RestauraRios - CIREF","description":"Revista de conservaci\u00f3n y restauraci\u00f3n fluvial","publisher":{"@id":"https:\/\/restaurarios.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/restaurarios.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/restaurarios.es\/#organization","name":"Revista RestauraRios - CIREF","url":"https:\/\/restaurarios.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/restaurarios.es\/#\/schema\/logo\/image\/","url":"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/cabecera-960px.jpg","contentUrl":"https:\/\/restaurarios.es\/wp-content\/uploads\/2022\/07\/cabecera-960px.jpg","width":960,"height":214,"caption":"Revista RestauraRios - CIREF"},"image":{"@id":"https:\/\/restaurarios.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/restaurarios.es\/#\/schema\/person\/9c0a72e763764be8ca350ac61d81581d","name":"fixer","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/restaurarios.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56f32ef8ea937be7ae878c3db40e980c3e945311aa3045db59fa797cc9ae49ab?s=96&d=mm&r=g","caption":"fixer"},"sameAs":["http:\/\/cirefluvial.com\/nuevarevista"],"url":"https:\/\/restaurarios.es\/pt\/author\/fixer\/"}]}},"_links":{"self":[{"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/posts\/259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/comments?post=259"}],"version-history":[{"count":4,"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/posts\/259\/revisions"}],"predecessor-version":[{"id":377,"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/posts\/259\/revisions\/377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/media\/15"}],"wp:attachment":[{"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/media?parent=259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/categories?post=259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/restaurarios.es\/pt\/wp-json\/wp\/v2\/tags?post=259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}